{"id":1040,"date":"2019-05-30T14:40:13","date_gmt":"2019-05-30T12:40:13","guid":{"rendered":"http:\/\/www.landfrauenverein-hameln.de\/?p=1040"},"modified":"2019-09-21T12:57:02","modified_gmt":"2019-09-21T10:57:02","slug":"landfrauen-suchen-urlaubslektuere","status":"publish","type":"post","link":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/","title":{"rendered":"Landfrauen suchen Urlaubslekt\u00fcre"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\"><strong>L<\/strong>Bis auf den allerletzten Platz war die <strong>Buchhandlung von Blum<\/strong> in der Emmernstra\u00dfe von den Hamelner Landfrauen besetzt. Vom Cateringteam des Kaffees <strong>Relax<\/strong> mit Getr\u00e4nken und Kuchen gut betreut, lauschten sie den Worten von <strong>Frau Cornelie von Blum<\/strong> und ihrer Kollegin <strong>Katrin Spie\u00df<\/strong>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Insgesamt wurden 24 B\u00fccher von den beiden Damen beschrieben. Die ausliegenden Empfehlungslisten wurden ausgiebig genutzt, mit vielen Infos versehen und die interessantesten Titel markiert. So ist man auch f\u00fcr zuk\u00fcnftige Buchk\u00e4ufe gut ger\u00fcstet.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00dcber das Leben von starken Frauen wurde berichtet \u2013 von Frauen, deren Lebensgrundlage schlecht war, die sich aber nach und nach durch Hilfe anderer Personen oder Umst\u00e4nden st\u00e4rken und vermutlich ihr Leben in den Griff oder zumindest lebenswerter gestalten konnten: Die Werke <strong>Alte Sorten<\/strong> von Michael Arenz, <strong>Der Zopf<\/strong> von Laetitia Colombani, <strong>Suleika \u00f6ffnet die Augen<\/strong> von Gusel Jachina, <strong>Die Herrenausstatterin<\/strong> von Mariana Leky um nur einige zu nennen. Das jeweilige Ende wurde von den Damen nat\u00fcrlich nicht preisgegeben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Auch Beziehungsprobleme kamen in der Vorstellung nicht zu kurz: <strong>Herz auf Eis<\/strong> von Isabell Autissier beschreibt die Probleme eines Kinderlosen Ehepaars, das sechs Monate in der Arktis festsitzt. <strong>Der<\/strong> <strong>Sommer meiner Mutter<\/strong> von Ulrich Woelk beschreibt die Mondlandung 1969 und das Leben einer Familie im Umbruch. <strong>Weg <\/strong>von Doris Knecht zeigt die Suche eines getrennt\u00a0 lebenden Ehepaars nach ihrer Tochter. In <strong>Drei Tage und ein Leben<\/strong> von Pierre Lemaitre wird ein vermisster Junge gesucht. Das Buch <strong>Die Suche<\/strong> von Charlotte Link landet direkt im Bereich Kriminalroman: Der Fall von zwei toten und einem vermissten M\u00e4dchen bringen eine Kommissarin in Schottland auf den Plan.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Auch das Thema Geschichte wurde anschaulich dargestellt: <strong>Martha tanzt <\/strong>von Tom Saller l\u00e4sst die 30-er Jahre aufleben. <strong>B\u00fchlerh\u00f6he<\/strong> von Brigitte Glaser beschreibt die 50-er Jahre, ebenso wie <strong>Hotel Laguna<\/strong> von Alexander Gorkow. <strong>Ein Gentleman in Moskau <\/strong>von Amor Towles gibt Einblicke in die Zeit von Lenin und Stalin; <strong>Schnell dein Leben <\/strong>von Sylvie Schenk spielt in der Nachkriegszeit und den Schwierigkeiten zwischen einem franz\u00f6sisch \/ deutschen Liebespaar.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Die 40-er Jahre werden durch <strong>Der Frauenchor von Chilbury <\/strong>von Jennifer Ryan beleuchtet; hierbei kommt das Thema Zusammenhalt ins Spiel; ebenso wie in <strong>Steeple Sinderby<\/strong> von J. L. Carr einem witzigen Buch um die Erlangung eines Fu\u00dfball Pokals in einem englischen Dorfes; wobei <strong>Der Wal <\/strong>von \u00a0John Ironmonger den Zusammenhalt eines Dorfes in Cornwall erfordert.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Interessant erscheinen auch die B\u00fccher <strong>Drei Frauen am See <\/strong>von Dora Heldt, <strong>Ein Monat auf dem Land <\/strong>ebenfalls von J. L. Carr und nicht zuletzt das Lieblingsbuch von Frau von Blum: Rendezvous mit einem Oktopus von Sy Montgomery.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Mit reichlich neuem Wissen und einigen B\u00fcchern unterm Arm wurde ein sch\u00f6ner Nachmittag beendet.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>LBis auf den allerletzten Platz war die Buchhandlung von Blum in der Emmernstra\u00dfe von den Hamelner Landfrauen besetzt. Vom Cateringteam des Kaffees Relax mit Getr\u00e4nken und Kuchen gut betreut, lauschten sie den Worten von Frau Cornelie von Blum und ihrer Kollegin Katrin Spie\u00df. Insgesamt wurden 24 B\u00fccher von den beiden Damen beschrieben. Die ausliegenden Empfehlungslisten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[],"class_list":["post-1040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landfrauen suchen Urlaubslekt\u00fcre - Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landfrauen suchen Urlaubslekt\u00fcre - Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ\" \/>\n<meta property=\"og:description\" content=\"LBis auf den allerletzten Platz war die Buchhandlung von Blum in der Emmernstra\u00dfe von den Hamelner Landfrauen besetzt. Vom Cateringteam des Kaffees Relax mit Getr\u00e4nken und Kuchen gut betreut, lauschten sie den Worten von Frau Cornelie von Blum und ihrer Kollegin Katrin Spie\u00df. Insgesamt wurden 24 B\u00fccher von den beiden Damen beschrieben. Die ausliegenden Empfehlungslisten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/\" \/>\n<meta property=\"og:site_name\" content=\"Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-30T12:40:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-21T10:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.landfrauenverein-hameln.de\/wp-content\/uploads\/2019\/05\/Buchladenbesuch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3264\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Kiewaldt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Kiewaldt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/\"},\"author\":{\"name\":\"Laura Kiewaldt\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/#\\\/schema\\\/person\\\/52de5d9c57ea0db19cea8b8fec308f3e\"},\"headline\":\"Landfrauen suchen Urlaubslekt\u00fcre\",\"datePublished\":\"2019-05-30T12:40:13+00:00\",\"dateModified\":\"2019-09-21T10:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/\"},\"wordCount\":451,\"image\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Buchladenbesuch.jpg\",\"articleSection\":[\"Archiv\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/\",\"url\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/\",\"name\":\"Landfrauen suchen Urlaubslekt\u00fcre - Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Buchladenbesuch.jpg\",\"datePublished\":\"2019-05-30T12:40:13+00:00\",\"dateModified\":\"2019-09-21T10:57:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/#\\\/schema\\\/person\\\/52de5d9c57ea0db19cea8b8fec308f3e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Buchladenbesuch.jpg\",\"contentUrl\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Buchladenbesuch.jpg\",\"width\":3264,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/2019\\\/05\\\/30\\\/landfrauen-suchen-urlaubslektuere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landfrauen suchen Urlaubslekt\u00fcre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/#website\",\"url\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/\",\"name\":\"Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ\",\"description\":\"Wir sind ein Verein f\u00fcr Frauen jeden Alters, aus allen Berufsgruppen vom Land und aus der Stadt.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/#\\\/schema\\\/person\\\/52de5d9c57ea0db19cea8b8fec308f3e\",\"name\":\"Laura Kiewaldt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ea18ab8d83fccbd1d64acb9b61e4c79ccd5b83bc41f518498c3c251a944d8bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ea18ab8d83fccbd1d64acb9b61e4c79ccd5b83bc41f518498c3c251a944d8bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ea18ab8d83fccbd1d64acb9b61e4c79ccd5b83bc41f518498c3c251a944d8bf?s=96&d=mm&r=g\",\"caption\":\"Laura Kiewaldt\"},\"url\":\"https:\\\/\\\/www.landfrauenverein-hameln.de\\\/index.php\\\/author\\\/brockmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landfrauen suchen Urlaubslekt\u00fcre - Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/","og_locale":"de_DE","og_type":"article","og_title":"Landfrauen suchen Urlaubslekt\u00fcre - Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ","og_description":"LBis auf den allerletzten Platz war die Buchhandlung von Blum in der Emmernstra\u00dfe von den Hamelner Landfrauen besetzt. Vom Cateringteam des Kaffees Relax mit Getr\u00e4nken und Kuchen gut betreut, lauschten sie den Worten von Frau Cornelie von Blum und ihrer Kollegin Katrin Spie\u00df. Insgesamt wurden 24 B\u00fccher von den beiden Damen beschrieben. Die ausliegenden Empfehlungslisten [&hellip;]","og_url":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/","og_site_name":"Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ","article_published_time":"2019-05-30T12:40:13+00:00","article_modified_time":"2019-09-21T10:57:02+00:00","og_image":[{"width":3264,"height":2448,"url":"https:\/\/www.landfrauenverein-hameln.de\/wp-content\/uploads\/2019\/05\/Buchladenbesuch.jpg","type":"image\/jpeg"}],"author":"Laura Kiewaldt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Laura Kiewaldt","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#article","isPartOf":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/"},"author":{"name":"Laura Kiewaldt","@id":"https:\/\/www.landfrauenverein-hameln.de\/#\/schema\/person\/52de5d9c57ea0db19cea8b8fec308f3e"},"headline":"Landfrauen suchen Urlaubslekt\u00fcre","datePublished":"2019-05-30T12:40:13+00:00","dateModified":"2019-09-21T10:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/"},"wordCount":451,"image":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.landfrauenverein-hameln.de\/wp-content\/uploads\/2019\/05\/Buchladenbesuch.jpg","articleSection":["Archiv"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/","url":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/","name":"Landfrauen suchen Urlaubslekt\u00fcre - Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ","isPartOf":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#primaryimage"},"image":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.landfrauenverein-hameln.de\/wp-content\/uploads\/2019\/05\/Buchladenbesuch.jpg","datePublished":"2019-05-30T12:40:13+00:00","dateModified":"2019-09-21T10:57:02+00:00","author":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/#\/schema\/person\/52de5d9c57ea0db19cea8b8fec308f3e"},"breadcrumb":{"@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#primaryimage","url":"https:\/\/www.landfrauenverein-hameln.de\/wp-content\/uploads\/2019\/05\/Buchladenbesuch.jpg","contentUrl":"https:\/\/www.landfrauenverein-hameln.de\/wp-content\/uploads\/2019\/05\/Buchladenbesuch.jpg","width":3264,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/2019\/05\/30\/landfrauen-suchen-urlaubslektuere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.landfrauenverein-hameln.de\/"},{"@type":"ListItem","position":2,"name":"Landfrauen suchen Urlaubslekt\u00fcre"}]},{"@type":"WebSite","@id":"https:\/\/www.landfrauenverein-hameln.de\/#website","url":"https:\/\/www.landfrauenverein-hameln.de\/","name":"Landfrauenverein Hameln - weiblich, l\u00e4ndlich, innovativ","description":"Wir sind ein Verein f\u00fcr Frauen jeden Alters, aus allen Berufsgruppen vom Land und aus der Stadt.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.landfrauenverein-hameln.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.landfrauenverein-hameln.de\/#\/schema\/person\/52de5d9c57ea0db19cea8b8fec308f3e","name":"Laura Kiewaldt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8ea18ab8d83fccbd1d64acb9b61e4c79ccd5b83bc41f518498c3c251a944d8bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ea18ab8d83fccbd1d64acb9b61e4c79ccd5b83bc41f518498c3c251a944d8bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ea18ab8d83fccbd1d64acb9b61e4c79ccd5b83bc41f518498c3c251a944d8bf?s=96&d=mm&r=g","caption":"Laura Kiewaldt"},"url":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/author\/brockmann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/posts\/1040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/comments?post=1040"}],"version-history":[{"count":2,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/posts\/1040\/revisions"}],"predecessor-version":[{"id":1074,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/posts\/1040\/revisions\/1074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/media\/1039"}],"wp:attachment":[{"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/media?parent=1040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/categories?post=1040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.landfrauenverein-hameln.de\/index.php\/wp-json\/wp\/v2\/tags?post=1040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}